{"id":1954,"date":"2019-06-13T12:28:26","date_gmt":"2019-06-13T12:28:26","guid":{"rendered":"https:\/\/floorballindia.com\/InFF\/?page_id=1954"},"modified":"2019-06-27T09:46:41","modified_gmt":"2019-06-27T09:46:41","slug":"national-workshop-clinic","status":"publish","type":"page","link":"https:\/\/floorballindia.com\/InFF\/national-workshop-clinic\/","title":{"rendered":"National Workshop &#038; Clinic"},"content":{"rendered":"<section id=\"bt_bb_section6a04a2887d417\" class=\"bt_bb_section bt_bb_layout_boxed_900 bt_bb_vertical_align_top bt_bb_top_spacing_medium bt_bb_bottom_spacing_medium\"  data-bt-override-class=\"null\"><div class=\"bt_bb_port\"><div class=\"bt_bb_cell\"><div class=\"bt_bb_cell_inner\"><div class=\"bt_bb_row \"  data-bt-override-class=\"{}\"><div class=\"bt_bb_row_holder\" ><div  class=\"bt_bb_column col-xxl-12 col-xl-12 bt_bb_vertical_align_top bt_bb_align_left bt_bb_padding_normal\" style=\"; --column-width:12;\" data-width=\"12\" data-bt-override-class=\"{}\"><div class=\"bt_bb_column_content\"><div class=\"bt_bb_column_content_inner\"><header class=\"bt_bb_headline bt_bb_dash_none bt_bb_size_inherit bt_bb_align_inherit\" data-bt-override-class=\"{}\"><h5 style=\"font-size:18px\" class=\"bt_bb_headline_tag\"><span class=\"bt_bb_headline_content\"><span>National Workshop &amp; Clinic<\/span><\/span><\/h5><\/header><\/div><\/div><\/div><\/div><\/div><div class=\"bt_bb_row \"  data-bt-override-class=\"{}\"><div class=\"bt_bb_row_holder\" ><div  class=\"bt_bb_column col-xxl-12 col-xl-12 bt_bb_vertical_align_top bt_bb_align_left bt_bb_padding_normal\" style=\"; --column-width:12;\" data-width=\"12\" data-bt-override-class=\"{}\"><div class=\"bt_bb_column_content\"><div class=\"bt_bb_column_content_inner\"><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_top_spacing_medium\" data-bt-override-class=\"null\"><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"bt_bb_row \"  data-bt-override-class=\"{}\"><div class=\"bt_bb_row_holder\" ><div  class=\"bt_bb_column col-xxl-12 col-xl-12 bt_bb_vertical_align_top bt_bb_align_left bt_bb_padding_normal\" style=\"; --column-width:12;\" data-width=\"12\" data-bt-override-class=\"{}\"><div class=\"bt_bb_column_content\"><div class=\"bt_bb_column_content_inner\"><div class=\"bt_bb_image bt_bb_shape_square bt_bb_target_self bt_bb_align_inherit bt_bb_hover_style_simple bt_bb_content_display_always bt_bb_content_align_middle\" data-bt-override-class=\"{}\"><span><img decoding=\"async\" src=\"https:\/\/floorballindia.com\/InFF\/wp-content\/plugins\/bold-page-builder\/img\/placeholder.png\" alt=\"Placeholder image\" title=\"Placeholder image\"><\/span><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"bt_bb_row \"  data-bt-override-class=\"{}\"><div class=\"bt_bb_row_holder\" ><div  class=\"bt_bb_column col-xxl-12 col-xl-12 bt_bb_vertical_align_top bt_bb_align_left bt_bb_padding_normal\" style=\"; --column-width:12;\" data-width=\"12\" data-bt-override-class=\"{}\"><div class=\"bt_bb_column_content\"><div class=\"bt_bb_column_content_inner\"><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_top_spacing_medium\" data-bt-override-class=\"null\"><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"bt_bb_row \"  data-bt-override-class=\"{}\"><div class=\"bt_bb_row_holder\" ><div  class=\"bt_bb_column col-xxl-12 col-xl-12 bt_bb_vertical_align_top bt_bb_align_left bt_bb_padding_normal\" style=\"; --column-width:12;\" data-width=\"12\" data-bt-override-class=\"{}\"><div class=\"bt_bb_column_content\"><div class=\"bt_bb_column_content_inner\"><\/div><\/div><\/div><\/div><\/div><div class=\"bt_bb_row \"  data-bt-override-class=\"{}\"><div class=\"bt_bb_row_holder\" ><div  class=\"bt_bb_column col-xxl-12 col-xl-12 bt_bb_vertical_align_top bt_bb_align_left bt_bb_padding_normal\" style=\"; --column-width:12;\" data-width=\"12\" data-bt-override-class=\"{}\"><div class=\"bt_bb_column_content\"><div class=\"bt_bb_column_content_inner\"><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_top_spacing_medium\" data-bt-override-class=\"null\"><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"bt_bb_row \"  data-bt-override-class=\"{}\"><div class=\"bt_bb_row_holder\" ><div  class=\"bt_bb_column col-xxl-12 col-xl-12 bt_bb_vertical_align_top bt_bb_align_left bt_bb_padding_normal\" style=\"; --column-width:12;\" data-width=\"12\" data-bt-override-class=\"{}\"><div class=\"bt_bb_column_content\"><div class=\"bt_bb_column_content_inner\"><div class=\"bt_bb_image bt_bb_shape_square bt_bb_target_self bt_bb_align_inherit bt_bb_hover_style_simple bt_bb_content_display_always bt_bb_content_align_middle\" data-bt-override-class=\"{}\"><span><img decoding=\"async\" src=\"https:\/\/floorballindia.com\/InFF\/wp-content\/plugins\/bold-page-builder\/img\/placeholder.png\" alt=\"Placeholder image\" title=\"Placeholder image\"><\/span><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"bt_bb_row \"  data-bt-override-class=\"{}\"><div class=\"bt_bb_row_holder\" ><div  class=\"bt_bb_column col-xxl-12 col-xl-12 bt_bb_vertical_align_top bt_bb_align_left bt_bb_padding_normal\" style=\"; --column-width:12;\" data-width=\"12\" data-bt-override-class=\"{}\"><div class=\"bt_bb_column_content\"><div class=\"bt_bb_column_content_inner\"><div class=\"bt_bb_separator bt_bb_border_style_none bt_bb_top_spacing_medium\" data-bt-override-class=\"null\"><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"bt_bb_row \"  data-bt-override-class=\"{}\"><div class=\"bt_bb_row_holder\" ><div  class=\"bt_bb_column col-xxl-12 col-xl-12 bt_bb_vertical_align_top bt_bb_align_left bt_bb_padding_normal\" style=\"; --column-width:12;\" data-width=\"12\" data-bt-override-class=\"{}\"><div class=\"bt_bb_column_content\"><div class=\"bt_bb_column_content_inner\"><\/div><\/div><\/div><\/div><\/div><\/div><!-- cell_inner --><\/div><!-- cell --><\/div><!-- port --><\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":2651,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1954","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/floorballindia.com\/InFF\/wp-json\/wp\/v2\/pages\/1954","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/floorballindia.com\/InFF\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/floorballindia.com\/InFF\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/floorballindia.com\/InFF\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/floorballindia.com\/InFF\/wp-json\/wp\/v2\/comments?post=1954"}],"version-history":[{"count":5,"href":"https:\/\/floorballindia.com\/InFF\/wp-json\/wp\/v2\/pages\/1954\/revisions"}],"predecessor-version":[{"id":2706,"href":"https:\/\/floorballindia.com\/InFF\/wp-json\/wp\/v2\/pages\/1954\/revisions\/2706"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/floorballindia.com\/InFF\/wp-json\/wp\/v2\/media\/2651"}],"wp:attachment":[{"href":"https:\/\/floorballindia.com\/InFF\/wp-json\/wp\/v2\/media?parent=1954"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}