{"id":2637,"date":"2019-06-26T11:15:08","date_gmt":"2019-06-26T11:15:08","guid":{"rendered":"https:\/\/floorballindia.com\/InFF\/?page_id=2637"},"modified":"2019-06-26T11:47:12","modified_gmt":"2019-06-26T11:47:12","slug":"delhi-champions","status":"publish","type":"page","link":"https:\/\/floorballindia.com\/InFF\/delhi-champions\/","title":{"rendered":"delhi-champions"},"content":{"rendered":"<section id=\"bt_bb_section6a04fb7496b81\" class=\"bt_bb_section bt_bb_layout_boxed_900 bt_bb_vertical_align_top bt_bb_top_spacing_medium bt_bb_bottom_spacing_medium\"  data-bt-override-class=\"null\"><div class=\"bt_bb_port\"><div class=\"bt_bb_cell\"><div class=\"bt_bb_cell_inner\"><div class=\"bt_bb_row \"  data-bt-override-class=\"{}\"><div class=\"bt_bb_row_holder\" ><div  class=\"bt_bb_column col-xxl-6 col-xl-6 bt_bb_vertical_align_top bt_bb_align_left bt_bb_padding_normal\" style=\"; --column-width:6;\" data-width=\"6\" data-bt-override-class=\"{}\"><div class=\"bt_bb_column_content\"><div class=\"bt_bb_column_content_inner\"><div  class=\"bt_bb_text\" ><\/p>\n<p>Club Secretary:<br \/>\n<strong>Dr. Deepak Saxena<\/strong><\/p>\n<p>Add: 76, Unique Apartment, Plot No.- 2,<br \/>\nSector-13, Rohini, Delhi-110085<\/p>\n<p>Mobile No.: 8800369683<\/p>\n<p>Email: dipaksaxena4u@gmail.com<\/p>\n<p>\n<\/div><\/div><\/div><\/div><div  class=\"bt_bb_column col-xxl-6 col-xl-6 bt_bb_vertical_align_top bt_bb_align_right bt_bb_padding_normal\" style=\"; --column-width:6;\" data-width=\"6\" data-bt-override-class=\"{}\"><div class=\"bt_bb_column_content\"><div class=\"bt_bb_column_content_inner\"><div class=\"bt_bb_image bt_bb_shape_square bt_bb_target_self bt_bb_align_inherit bt_bb_hover_style_simple bt_bb_content_display_always bt_bb_content_align_middle\" data-bt-override-class=\"{}\"><span><img loading=\"lazy\" decoding=\"async\" width=\"180\" height=\"180\" src=\"https:\/\/floorballindia.com\/InFF\/wp-content\/uploads\/2019\/06\/delhi-champ.jpg\" class=\"attachment-full size-full\" alt=\"https:\/\/floorballindia.com\/InFF\/wp-content\/uploads\/2019\/06\/delhi-champ.jpg\" data-full_image_src=\"https:\/\/floorballindia.com\/InFF\/wp-content\/uploads\/2019\/06\/delhi-champ.jpg\" title=\"delhi-champ\" srcset=\"https:\/\/floorballindia.com\/InFF\/wp-content\/uploads\/2019\/06\/delhi-champ.jpg 180w, https:\/\/floorballindia.com\/InFF\/wp-content\/uploads\/2019\/06\/delhi-champ-160x160.jpg 160w\" sizes=\"auto, (max-width: 180px) 100vw, 180px\" \/><\/span><\/div><\/div><\/div><\/div><\/div><\/div><\/div><!-- cell_inner --><\/div><!-- cell --><\/div><!-- port --><\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":2651,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2637","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/floorballindia.com\/InFF\/wp-json\/wp\/v2\/pages\/2637","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/floorballindia.com\/InFF\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/floorballindia.com\/InFF\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/floorballindia.com\/InFF\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/floorballindia.com\/InFF\/wp-json\/wp\/v2\/comments?post=2637"}],"version-history":[{"count":5,"href":"https:\/\/floorballindia.com\/InFF\/wp-json\/wp\/v2\/pages\/2637\/revisions"}],"predecessor-version":[{"id":2654,"href":"https:\/\/floorballindia.com\/InFF\/wp-json\/wp\/v2\/pages\/2637\/revisions\/2654"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/floorballindia.com\/InFF\/wp-json\/wp\/v2\/media\/2651"}],"wp:attachment":[{"href":"https:\/\/floorballindia.com\/InFF\/wp-json\/wp\/v2\/media?parent=2637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}