{"id":3587,"date":"2021-02-06T06:05:20","date_gmt":"2021-02-06T06:05:20","guid":{"rendered":"https:\/\/floorballindia.com\/InFF\/?page_id=3587"},"modified":"2021-06-25T12:46:17","modified_gmt":"2021-06-25T12:46:17","slug":"resource-mobilization-committee","status":"publish","type":"page","link":"https:\/\/floorballindia.com\/InFF\/resource-mobilization-committee\/","title":{"rendered":"RESOURCE MOBILIZATION COMMITTEE"},"content":{"rendered":"<section id=\"bt_bb_section6a0494d040574\" class=\"bt_bb_section bt_bb_layout_boxed_900 bt_bb_vertical_align_top bt_bb_top_spacing_medium bt_bb_bottom_spacing_medium\"  data-bt-override-class=\"null\"><div class=\"bt_bb_port\"><div class=\"bt_bb_cell\"><div class=\"bt_bb_cell_inner\"><div class=\"bt_bb_row \"  data-bt-override-class=\"{}\"><div class=\"bt_bb_row_holder\" ><div  class=\"bt_bb_column col-xxl-12 col-xl-12 bt_bb_vertical_align_top bt_bb_align_left bt_bb_padding_normal\" style=\"; --column-width:12;\" data-width=\"12\" data-bt-override-class=\"{}\"><div class=\"bt_bb_column_content\"><div class=\"bt_bb_column_content_inner\"><header class=\"bt_bb_headline bt_bb_dash_none bt_bb_size_inherit bt_bb_align_inherit\" style=\";color:#0066bf;border-color:#0066bf;\" data-bt-override-class=\"{}\"><h3 class=\"bt_bb_headline_tag\"><span class=\"bt_bb_headline_content\"><span>RESOURCE MOBILIZATION COMMITTEE<\/span><\/span><\/h3><\/header><div  class=\"bt_bb_text\" ><\/p>\n<p>1. Sh. Baldev Sharma \u2013 Convener<br \/>\n2. Sh. Ravindra Chothave, Maharashtra \u2013 Co &#8211; Convener<br \/>\n3. Sh. Baldev Sharma \u2013 Co &#8211; Convener<br \/>\n4. Sh. Prijo Johny TJ, Karnataka<br \/>\n5. Sh. Suresh Kumar, Delhi<br \/>\n6. Sh. Dinesh Kaushik, Delhi<br \/>\n7. Sh. Dinesh Sharma, Delhi<br \/>\n8. Sh. Sanjeev Matta, Delhi<br \/>\n9. Sh. Rajesh Kaushik, Delhi<br \/>\n10. Sh. Surjeet Nain, Haryana<\/p>\n<p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><!-- cell_inner --><\/div><!-- cell --><\/div><!-- port --><\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":3352,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3587","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/floorballindia.com\/InFF\/wp-json\/wp\/v2\/pages\/3587","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/floorballindia.com\/InFF\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/floorballindia.com\/InFF\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/floorballindia.com\/InFF\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/floorballindia.com\/InFF\/wp-json\/wp\/v2\/comments?post=3587"}],"version-history":[{"count":3,"href":"https:\/\/floorballindia.com\/InFF\/wp-json\/wp\/v2\/pages\/3587\/revisions"}],"predecessor-version":[{"id":3623,"href":"https:\/\/floorballindia.com\/InFF\/wp-json\/wp\/v2\/pages\/3587\/revisions\/3623"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/floorballindia.com\/InFF\/wp-json\/wp\/v2\/media\/3352"}],"wp:attachment":[{"href":"https:\/\/floorballindia.com\/InFF\/wp-json\/wp\/v2\/media?parent=3587"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}